{"id":3359,"date":"2025-11-11T11:50:32","date_gmt":"2025-11-11T16:50:32","guid":{"rendered":"https:\/\/www.cipcdahuaraz.org\/cip\/services-3\/"},"modified":"2026-01-03T12:21:43","modified_gmt":"2026-01-03T17:21:43","slug":"convenio","status":"publish","type":"page","link":"https:\/\/www.cipcdahuaraz.org\/cip\/convenio\/","title":{"rendered":"Convenio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3359\" class=\"elementor elementor-3359\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8828dd8 elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default elementor-invisible\" data-id=\"8828dd8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:1869,&quot;url&quot;:&quot;https:\\\/\\\/www.cipcdahuaraz.org\\\/zip\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/banner07.png&quot;},{&quot;id&quot;:1865,&quot;url&quot;:&quot;https:\\\/\\\/www.cipcdahuaraz.org\\\/zip\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/banner06.png&quot;}],&quot;animation&quot;:&quot;zoomIn&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d43801\" data-id=\"6d43801\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a9b4e4 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"9a9b4e4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca11b8a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca11b8a\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cabb379\" data-id=\"cabb379\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0507094 e-flex e-con-boxed e-con e-parent\" data-id=\"0507094\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8183d93 elementor-widget elementor-widget-html\" data-id=\"8183d93\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<!-- Carrusel de Convenios CIP con Swiper -->\r\n<link\r\n  rel=\"stylesheet\"\r\n  href=\"https:\/\/cdn.jsdelivr.net\/npm\/swiper@11\/swiper-bundle.min.css\"\r\n\/>\r\n\r\n<div class=\"cip-swiper-container swiper\">\r\n  <div class=\"swiper-wrapper\">\r\n                 <!-- Slide 1 -->\r\n    <div class=\"swiper-slide\">\r\n      <div class=\"cip-slide\">\r\n        <img decoding=\"async\" src=\"https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio_postg.png\" \/>\r\n        <div class=\"cip-slide-content\">\r\n          <h3>Escuela de Post Grado-UNASAM<\/h3>\r\n          <p>Alianza Estrategica entre la Escuela de Post Grado de la UNASAM y el CIP-CDA-Huaraz<\/p>\r\n          <button\r\n            class=\"cip-btn-ver\"\r\n            onclick=\"verConvenio(event, 'https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio_post.pdf')\"\r\n          >Ver Convenio<\/button>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n                           <!-- Slide 1 -->\r\n    <div class=\"swiper-slide\">\r\n      <div class=\"cip-slide\">\r\n        <img decoding=\"async\" src=\"https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio_piura.png\" \/>\r\n        <div class=\"cip-slide-content\">\r\n          <h3>JRD-CIP CD Piura<\/h3>\r\n          <p>Alianza Estrategica entre el CIP-CD-Piura y el CIP-CDA-Huaraz<\/p>\r\n          <button\r\n            class=\"cip-btn-ver\"\r\n            onclick=\"verConvenio(event, 'https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio_jrd.pdf')\"\r\n          >Ver Convenio<\/button>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n                      <!-- Slide 1 -->\r\n    <div class=\"swiper-slide\">\r\n      <div class=\"cip-slide\">\r\n        <img decoding=\"async\" src=\"https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio_guia.png\" alt=\"guias\" \/>\r\n        <div class=\"cip-slide-content\">\r\n          <h3>Casa de Guias Huaraz<\/h3>\r\n          <p>Descuentos Especiales en su servicio de Centro de Idiomas y otros.<\/p>\r\n          <button\r\n            class=\"cip-btn-ver\"\r\n            onclick=\"verConvenio(event, 'https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio_guias.pdf')\"\r\n          >Ver Convenio<\/button>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n                <!-- Slide 1 -->\r\n    <div class=\"swiper-slide\">\r\n      <div class=\"cip-slide\">\r\n        <img decoding=\"async\" src=\"https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio_lucila.png\" alt=\"castro\" \/>\r\n        <div class=\"cip-slide-content\">\r\n          <h3>Lucila Mayorista-Market<\/h3>\r\n          <p>Descuentos de hasta el 10% en compra de viveres.<\/p>\r\n          <button\r\n            class=\"cip-btn-ver\"\r\n            onclick=\"verConvenio(event, 'https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio_lucila.pdf')\"\r\n          >Ver Convenio<\/button>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n          <!-- Slide 1 -->\r\n    <div class=\"swiper-slide\">\r\n      <div class=\"cip-slide\">\r\n        <img decoding=\"async\" src=\"https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio_castro.png\" alt=\"castro\" \/>\r\n        <div class=\"cip-slide-content\">\r\n          <h3>Chochos Castro 2<\/h3>\r\n          <p>Descuentos de hasta el 10% en consumo de alimentos.<\/p>\r\n          <button\r\n            class=\"cip-btn-ver\"\r\n            onclick=\"verConvenio(event, 'https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio_castro.pdf')\"\r\n          >Ver Convenio<\/button>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n    <!-- Slide 1 -->\r\n    <div class=\"swiper-slide\">\r\n      <div class=\"cip-slide\">\r\n        <img decoding=\"async\" src=\"https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/10\/KIES.png\" alt=\"KIES\" \/>\r\n        <div class=\"cip-slide-content\">\r\n          <h3>Centro Odontol\u00f3gico KIES<\/h3>\r\n          <p>Descuentos de hasta el 41% en servicios odontol\u00f3gicos. Cuidamos tu sonrisa, respaldamos tu salud.<\/p>\r\n          <button\r\n            class=\"cip-btn-ver\"\r\n            onclick=\"verConvenio(event, 'https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio01_kies.pdf')\"\r\n          >Ver Convenio<\/button>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <!-- Slide 2 -->\r\n    <div class=\"swiper-slide\">\r\n      <div class=\"cip-slide\">\r\n        <img decoding=\"async\" src=\"https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/10\/INFRAVIAL.png\" alt=\"GZA Infravial\" \/>\r\n        <div class=\"cip-slide-content\">\r\n          <h3>GZA Infravial Per\u00fa<\/h3>\r\n          <p>Especialistas en Ingenier\u00eda Vial y nuevas tecnolog\u00edas para obras nacionales e internacionales.<\/p>\r\n          <button\r\n            class=\"cip-btn-ver\"\r\n            onclick=\"verConvenio(event, 'https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio02_gza_infr.pdf')\"\r\n          >Ver Convenio<\/button>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <!-- Slide 3 -->\r\n    <div class=\"swiper-slide\">\r\n      <div class=\"cip-slide\">\r\n        <img decoding=\"async\" src=\"https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/asesoria.jpg\" alt=\"Asesor\u00eda Legal\" \/>\r\n        <div class=\"cip-slide-content\">\r\n          <h3>Estudio Jur\u00eddico Guti\u00e9rrez<\/h3>\r\n          <p>Asesor\u00eda legal especializada para ingenieros colegiados con descuentos de hasta el 30%.<\/p>\r\n          <button\r\n            class=\"cip-btn-ver\"\r\n            onclick=\"verConvenio(event, 'https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio_03.pdf')\"\r\n          >Ver Convenio<\/button>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <!-- Slide 4 -->\r\n    <div class=\"swiper-slide\">\r\n      <div class=\"cip-slide\">\r\n        <img decoding=\"async\" src=\"https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/10\/HUERTO-DE-LAZARO.png\" alt=\"Huerto de L\u00e1zaro\" \/>\r\n        <div class=\"cip-slide-content\">\r\n          <h3>Recreo Tur\u00edstico Huerto de L\u00e1zaro<\/h3>\r\n          <p>7% de descuento en comidas y bebidas no alcoh\u00f3licas para colegiados CIP\u2013CDA Huaraz.<\/p>\r\n          <button\r\n            class=\"cip-btn-ver\"\r\n            onclick=\"verConvenio(event, 'https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio04_huerto_lazaro.pdf')\"\r\n          >Ver Convenio<\/button>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n     <!-- Slide 5 -->\r\n    <div class=\"swiper-slide\">\r\n      <div class=\"cip-slide\">\r\n        <img decoding=\"async\" src=\"https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/10\/TAHUA.png\" alt=\"Tahua Gym\" \/>\r\n        <div class=\"cip-slide-content\">\r\n          <h3>Gimnasio Tahua Club<\/h3>\r\n          <p>Fortalece el equilibrio entre el desempe\u00f1o profesional y tu cuidado personal.\r\n\ud83d\udd39 Hasta 29% de descuento exclusivo para colegiados h\u00e1biles.<\/p>\r\n          <button\r\n            class=\"cip-btn-ver\"\r\n            onclick=\"verConvenio(event, 'https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio05_tahua_gym.pdf')\"\r\n          >Ver Convenio<\/button>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n\r\n     <!-- Slide 6 -->\r\n    <div class=\"swiper-slide\">\r\n      <div class=\"cip-slide\">\r\n        <img decoding=\"async\" src=\"https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/10\/CESAR-TOURS.png\" alt=\"Tahua Gym\" \/>\r\n        <div class=\"cip-slide-content\">\r\n          <h3>C\u00e9sar Tours<\/h3>\r\n          <p>20% de descuento en circuitos tur\u00edsticos a nivel nacional, en beneficio de los ingenieros habilitados del CIP-CDA-Huaraz.<\/p>\r\n          <button\r\n            class=\"cip-btn-ver\"\r\n            onclick=\"verConvenio(event, 'https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2025\/11\/convenio06_cesar_tours.pdf')\"\r\n          >Ver Convenio<\/button>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>    \r\n    \r\n        <!-- Slide 7 -->\r\n    <div class=\"swiper-slide\">\r\n      <div class=\"cip-slide\">\r\n        <img decoding=\"async\" src=\"\r\nhttps:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2026\/01\/civaz.jpg\" alt=\"Tahua Gym\" \/>\r\n        <div class=\"cip-slide-content\">\r\n          <h3>C\u00e9sar Tours<\/h3>\r\n          <p>20% de descuento para todos los colegiados habilitados del CIP-CDA-Huaraz, en cursos diplomados y especializaciones<\/p>\r\n          <button\r\n            class=\"cip-btn-ver\"\r\n            onclick=\"verConvenio(event, 'https:\/\/www.cipcdahuaraz.org\/cip\/wp-content\/uploads\/2026\/01\/convenio_civaz.pdf')\"\r\n          >Ver Convenio<\/button>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>    \r\n    \r\n  <\/div>\r\n\r\n  <!-- Controles -->\r\n  <div class=\"swiper-pagination\"><\/div>\r\n  <div class=\"swiper-button-prev\"><\/div>\r\n  <div class=\"swiper-button-next\"><\/div>\r\n<\/div>\r\n\r\n<script src=\"https:\/\/cdn.jsdelivr.net\/npm\/swiper@11\/swiper-bundle.min.js\"><\/script>\r\n<script src=\"https:\/\/cdn.jsdelivr.net\/npm\/swiper@11\/swiper-bundle.min.js\"><\/script>\r\n<script>\r\n  function verConvenio(event, url) {\r\n    event.stopPropagation();\r\n    window.open(url, \"_blank\", \"noopener,noreferrer\");\r\n  }\r\n\r\n  document.addEventListener(\"DOMContentLoaded\", () => {\r\n    const swiper = new Swiper(\".cip-swiper-container\", {\r\n      slidesPerView: 3,\r\n      spaceBetween: 24,\r\n      centeredSlides: false,\r\n      loop: true,\r\n      autoplay: {\r\n        delay: 5000,\r\n        disableOnInteraction: false,\r\n      },\r\n      pagination: {\r\n        el: \".swiper-pagination\",\r\n        clickable: true,\r\n      },\r\n      navigation: {\r\n        nextEl: \".swiper-button-next\",\r\n        prevEl: \".swiper-button-prev\",\r\n      },\r\n      breakpoints: {\r\n        0: { \r\n          slidesPerView: 1, \r\n          spaceBetween: 30, \r\n          centeredSlides: true \r\n        },\r\n        640: { slidesPerView: 2, spaceBetween: 25 },\r\n        1024: { slidesPerView: 3, spaceBetween: 30 }\r\n      }\r\n    });\r\n\r\n    \/\/ \u23f8 Pausar autoplay al pasar el cursor o tocar una card\r\n    const slides = document.querySelectorAll(\".cip-slide\");\r\n\r\n    slides.forEach(slide => {\r\n      \/\/ Pausa en hover (desktop)\r\n      slide.addEventListener(\"mouseenter\", () => swiper.autoplay.stop());\r\n      slide.addEventListener(\"mouseleave\", () => swiper.autoplay.start());\r\n\r\n      \/\/ Pausa en toque (m\u00f3vil)\r\n      slide.addEventListener(\"touchstart\", () => swiper.autoplay.stop());\r\n      slide.addEventListener(\"touchend\", () => swiper.autoplay.start());\r\n    });\r\n  });\r\n<\/script>\r\n\r\n<style>\r\n  :root {\r\n    --cip-red: #a00000;\r\n    --cip-beige: #f2e6ce;\r\n  }\r\n\r\n  .cip-swiper-container {\r\n    width: 100%;\r\n    padding: 45px 10px;\r\n    background: var(--cip-beige);\r\n    border-radius: 16px;\r\n    box-shadow: 0 4px 16px rgba(0,0,0,0.08);\r\n  }\r\n\r\n  .cip-slide {\r\n    position: relative;\r\n    border-radius: 14px;\r\n    overflow: hidden;\r\n    background: #fff;\r\n    max-width: 320px;\r\n    margin: auto;\r\n    box-shadow: 0 4px 10px rgba(0,0,0,0.12);\r\n    transition: transform 0.3s ease, box-shadow 0.3s ease;\r\n  }\r\n\r\n  .cip-slide:hover {\r\n    transform: translateY(-4px);\r\n    box-shadow: 0 6px 14px rgba(0,0,0,0.15);\r\n  }\r\n\r\n  .cip-slide img {\r\n    width: 100%;\r\n    height: 200px;\r\n    object-fit: cover;\r\n    transition: transform 0.4s ease;\r\n  }\r\n\r\n  .cip-slide:hover img {\r\n    transform: scale(1.05);\r\n  }\r\n\r\n  .cip-slide-content {\r\n    position: absolute;\r\n    bottom: 0;\r\n    left: 0;\r\n    right: 0;\r\n    background: rgba(160, 0, 0, 0.9);\r\n    color: white;\r\n    padding: 14px;\r\n    border-radius: 0 0 14px 14px;\r\n    transform: translateY(100%);\r\n    transition: transform 0.35s ease;\r\n  }\r\n\r\n  .cip-slide:hover .cip-slide-content,\r\n  .cip-slide:active .cip-slide-content {\r\n    transform: translateY(0);\r\n  }\r\n\r\n  .cip-slide-content h3 {\r\n    margin: 0 0 6px;\r\n    font-size: 1em;\r\n    color: var(--cip-beige);\r\n  }\r\n\r\n  .cip-slide-content p {\r\n    margin: 0 0 8px;\r\n    font-size: 0.85em;\r\n    line-height: 1.3;\r\n  }\r\n\r\n  .cip-btn-ver {\r\n    background-color: var(--cip-beige);\r\n    color: var(--cip-red);\r\n    border: none;\r\n    padding: 6px 12px;\r\n    border-radius: 6px;\r\n    cursor: pointer;\r\n    font-weight: bold;\r\n    font-size: 0.8em;\r\n    transition: all 0.2s;\r\n  }\r\n\r\n  .cip-btn-ver:hover {\r\n    background-color: #fff;\r\n    transform: scale(1.05);\r\n  }\r\n\r\n  \/* Swiper controles *\/\r\n  .swiper-button-next, .swiper-button-prev {\r\n    color: var(--cip-red);\r\n    transition: color 0.3s;\r\n  }\r\n  .swiper-button-next:hover, .swiper-button-prev:hover {\r\n    color: #700000;\r\n  }\r\n  .swiper-pagination-bullet-active {\r\n    background: var(--cip-red);\r\n  }\r\n\r\n  \/* Responsive - Mejor aspecto m\u00f3vil *\/\r\n  @media (max-width: 768px) {\r\n    .cip-slide {\r\n      max-width: 280px;\r\n      margin: 20px auto;\r\n    }\r\n    .cip-slide img {\r\n      height: 160px;\r\n    }\r\n    .cip-slide-content {\r\n      padding: 10px;\r\n    }\r\n    .cip-slide-content p {\r\n      font-size: 0.78em;\r\n    }\r\n    .cip-btn-ver {\r\n      font-size: 0.75em;\r\n      padding: 4px 8px;\r\n    }\r\n  }\r\n\r\n  @media (max-width: 480px) {\r\n    .cip-slide {\r\n      max-width: 260px;\r\n      margin: 25px auto;\r\n    }\r\n    .cip-slide img {\r\n      height: 150px;\r\n    }\r\n  }\r\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Escuela de Post Grado-UNASAM Alianza Estrategica entre la Escuela de Post Grado de la UNASAM y el CIP-CDA-Huaraz Ver Convenio JRD-CIP CD Piura Alianza Estrategica entre el CIP-CD-Piura y el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_kadence_starter_templates_imported_post":true,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"normal","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-3359","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.cipcdahuaraz.org\/cip\/wp-json\/wp\/v2\/pages\/3359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cipcdahuaraz.org\/cip\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cipcdahuaraz.org\/cip\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cipcdahuaraz.org\/cip\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cipcdahuaraz.org\/cip\/wp-json\/wp\/v2\/comments?post=3359"}],"version-history":[{"count":148,"href":"https:\/\/www.cipcdahuaraz.org\/cip\/wp-json\/wp\/v2\/pages\/3359\/revisions"}],"predecessor-version":[{"id":3778,"href":"https:\/\/www.cipcdahuaraz.org\/cip\/wp-json\/wp\/v2\/pages\/3359\/revisions\/3778"}],"wp:attachment":[{"href":"https:\/\/www.cipcdahuaraz.org\/cip\/wp-json\/wp\/v2\/media?parent=3359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}